{"id":8479,"date":"2020-09-01T18:02:08","date_gmt":"2020-09-01T16:02:08","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=8479"},"modified":"2020-09-01T18:02:08","modified_gmt":"2020-09-01T16:02:08","slug":"%e2%98%a3%ef%b8%8f-corona-und-eishockey-wettkampfsport-weiterhin-nicht-erlaubt-die-erhofften-lockerungen-im-sport-blieben-aus","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2020\/09\/01\/%e2%98%a3%ef%b8%8f-corona-und-eishockey-wettkampfsport-weiterhin-nicht-erlaubt-die-erhofften-lockerungen-im-sport-blieben-aus\/","title":{"rendered":"\u2623\ufe0f Corona und Eishockey: Wettkampfsport weiterhin nicht erlaubt!!!!!! &#8211; Die erhofften Lockerungen im Sport blieben aus."},"content":{"rendered":"<p class=\"id-Article-content-item id-Article-content-item-summary\"><span style=\"font-size: 18pt;\"><strong>Bayern &#8211; Die erhofften Lockerungen im Sport blieben aus. Staatsminister Florian Herrmann gab am Dienstag bekannt, dass der Wettkampfsport weiterhin nicht erlaubt wird. Dabei ging der Minister nicht einmal explizit auf den Sport ein.<br \/>\nNun muss eine Entscheidung her, ob auch der Start in der RHL in diesem Jahr noch m\u00f6glich ist oder nicht.<\/strong><\/span><\/p>\n<p class=\"id-Article-content-item id-Article-content-item-paragraph                           id-Article-content-item--first\">Der Umgang der bayerischen Regierung mit dem Amateursport und Breitensport entwickelt sich zu einer Farce. Klar ist: die Gesundheit der Spieler und Zuschauer geht vor. Doch worin liegt der Unterschied zwischen einem Konzertbesuch im Freien, der Besuch eines Biergartens oder dem Besuch eines Eishockeyspiels?<\/p>\n<p>Den \u00c4rger der Amateur- und Breitensportler hat sich die Staatsregierung aller sp\u00e4testens jetzt zugezogen.<\/p>\n<p class=\"id-Article-content-item id-Article-content-item-paragraph                           \"><strong>Die Ligenleitung wird mit jedem Teamleiter der RHL-Teams Mitte September ein Gespr\u00e4ch online f\u00fchren und \u00fcber die weiteren Schritte beraten und abstimmen.<\/strong><\/p>\n<p>Eishockeyteams und Stadien haben ihre Hausaufgaben im Vorfeld gemacht, haben ein \u00a0Hygienekonzept erarbeitet, mit dem auch der Infektionsschutz f\u00fcr Zuschauer gew\u00e4hrleistet ist.<\/p>\n<p>Doch die Regierung hat erneut einen Riegel vorgeschoben. Damit scheint der Start f\u00fcr die Saison 2020-2021 vom Tisch zu sein.<\/p>\n<p><span style=\"font-size: 18pt; color: #ff0000;\"><strong>Nun m\u00fcssen wir uns langsam die Frage stellen: Macht es wirklich Sinn noch auf einen Ligenstart in diesem Jahr und damit Lockerungen von Seiten der Politik zu hoffen.<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bayern &#8211; Die erhofften Lockerungen im Sport blieben aus. Staatsminister Florian Herrmann gab am Dienstag bekannt, dass der Wettkampfsport weiterhin nicht erlaubt wird. Dabei ging der Minister nicht einmal explizit auf den Sport ein. Nun muss eine Entscheidung her, ob auch der Start in der RHL in diesem Jahr noch m\u00f6glich ist oder nicht. Der &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2020\/09\/01\/%e2%98%a3%ef%b8%8f-corona-und-eishockey-wettkampfsport-weiterhin-nicht-erlaubt-die-erhofften-lockerungen-im-sport-blieben-aus\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;\u2623\ufe0f Corona und Eishockey: Wettkampfsport weiterhin nicht erlaubt!!!!!! &#8211; Die erhofften Lockerungen im Sport blieben aus.&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":8319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3],"tags":[101,90,56,85],"class_list":["post-8479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","tag-eishockey-in-rosenheim","tag-hobby-liga","tag-rhl-rosenheim-hockey-league-eishockey","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/8479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=8479"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/8479\/revisions"}],"predecessor-version":[{"id":8480,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/8479\/revisions\/8480"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/8319"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=8479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=8479"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=8479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}