{"id":6702,"date":"2019-03-29T02:06:15","date_gmt":"2019-03-29T01:06:15","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=6702"},"modified":"2019-03-29T02:06:15","modified_gmt":"2019-03-29T01:06:15","slug":"sheriffs-vs-bruckmuehl-32-2","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2019\/03\/29\/sheriffs-vs-bruckmuehl-32-2\/","title":{"rendered":"Sheriffs vs. Bruckm\u00fchl 3:2"},"content":{"rendered":"<p>Die Mangfall Sheriffs zeigen gegen den amtierenden Meister und Pokalrekordsieger EHC Bruckm\u00fchl einen gro\u00dfartigen Kampf und eine tolle Moral um den Einzug in das RHL-Finale. Am Ende setzen sich die Bruckm\u00fchler nach 2 Spielen mit einem Gesamtscore von 4:3 knapp durch. Die Sheriffs beenden die Saison 18\/19 auf Platz 3.<\/p>\n<p>GAMECENTER:\u00a0<a href=\"http:\/\/www.rhl-hockey.com\/w2\/event\/rhl-meister-playoff-halbfinale-b-vs-ehc-bruckmuehl\">http:\/\/www.rhl-hockey.com\/w2\/event\/rhl-meister-playoff-halbfinale-b-vs-ehc-bruckmuehl<\/a>\/<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Mangfall Sheriffs zeigen gegen den amtierenden Meister und Pokalrekordsieger EHC Bruckm\u00fchl einen gro\u00dfartigen Kampf und eine tolle Moral um den Einzug in das RHL-Finale. Am Ende setzen sich die Bruckm\u00fchler nach 2 Spielen mit einem Gesamtscore von 4:3 knapp durch. Die Sheriffs beenden die Saison 18\/19 auf Platz 3. GAMECENTER:\u00a0http:\/\/www.rhl-hockey.com\/w2\/event\/rhl-meister-playoff-halbfinale-b-vs-ehc-bruckmuehl\/ &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":4833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3,23],"tags":[85,51,21,54,20,18,15,53],"class_list":["post-6702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","category-rhl-1","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim","tag-eishockey-rosenheim","tag-hobbyliga","tag-hockey-league","tag-icehockey","tag-rhl","tag-rosenheim","tag-rosenheim-eishockey"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/6702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=6702"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/6702\/revisions"}],"predecessor-version":[{"id":6703,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/6702\/revisions\/6703"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/4833"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=6702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=6702"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=6702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}