{"id":5373,"date":"2018-09-14T15:23:15","date_gmt":"2018-09-14T13:23:15","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=5373"},"modified":"2018-09-14T15:23:15","modified_gmt":"2018-09-14T13:23:15","slug":"die-rhl-startet-mit-23-teams-in-die-neue-saison","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2018\/09\/14\/die-rhl-startet-mit-23-teams-in-die-neue-saison\/","title":{"rendered":"Die RHL startet mit 23 Teams in die neue Saison !!!!"},"content":{"rendered":"<p><span style=\"color: #000000;\">Am letzten Mittwoch fand die obligatorische Ligensitzung der RHL zum Start der 39. Spielzeit statt.<\/p>\n<p>Nach einigen Gespr\u00e4chen und Abstimmungen mit allen anwesenden RHL-Teamleitern fand man jedoch eine vern\u00fcnftige Basis und L\u00f6sung f\u00fcr die drei Leistungsgruppen der Liga.<\/p>\n<p>Begr\u00fc\u00dfen wollen wir auch zwei neue Teams in der RHL. Die Wild Boars Ebersberg gehen in der ersten Liga an den Start, und die Attel Haie Grafing nehmen in der 2. Liga teil.<\/p>\n<p>Somit gehen in dieser Spielzeit 23 Teams auf Punktejagd (<span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"http:\/\/www.rhl-hockey.com\/w2\/ergebnisse-tabelle-spielplan-statistik-1-liga-18-19\/\">8 Mannschaften in der RHL1<\/a><\/span> &#8211; <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/www.rhl-hockey.com\/w2\/ergebnisse-tabelle-spielplan-statistik-2-liga-18-19\/\">8 Mannschaften in der RHL2<\/a><\/span> &#8211; <span style=\"color: #00ff00;\"><a style=\"color: #00ff00;\" href=\"http:\/\/www.rhl-hockey.com\/w2\/ergebnisse-tabelle-spielplan-statistik-3-liga-18-19\/\">7 Mannschaften in der RHL3<\/a><\/span>)<\/p>\n<p>Zum 12. RHL-Ligapokal nehmen 18 RHL Teams teil. (Hier fehlen noch zwei Partien f\u00fcr das Achtelfinale, da das Finanzamt Rosenheim auf den Qualifikationssieger der Partie: Dirty Dangler vs EHC Bruckm\u00fchl &#8211; sowie die Wild Boars Ebersberg auf den Sieger der Partie: Aschau Rangers vs. Mangfall Sheriffs warten m\u00fcssen. \u00a0 \u00a0<a href=\"http:\/\/www.rhl-hockey.com\/w2\/12-rhl-ligapokal\/\">DIE SPIELE DER AUSLOSUNG HIER!!!!<\/a><\/p>\n<p><strong>Wir ben\u00f6tigen noch dringend Schiedsrichter!!!!!!!! &#8211; Also wer Lust hat meldet sich.<\/strong><\/p>\n<p><strong>Abgabe der Spielermeldelisten und Spielterminlisten ist der 15.10.2018!!!!!!! &#8211; Die 39. Saison wird gespielt von Anfang Oktober bis Ende M\u00e4rz.<\/strong><\/p>\n<p>Wir w\u00fcnschen allen Teams eine erfolgreiche und verletzungsfreie Saison. Der Spa\u00df und die Fairness an unserem Sport Eishockey steht dabei im absoluten Vordergrund!!!!!<\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am letzten Mittwoch fand die obligatorische Ligensitzung der RHL zum Start der 39. Spielzeit statt. Nach einigen Gespr\u00e4chen und Abstimmungen mit allen anwesenden RHL-Teamleitern fand man jedoch eine vern\u00fcnftige Basis und L\u00f6sung f\u00fcr die drei Leistungsgruppen der Liga. Begr\u00fc\u00dfen wollen wir auch zwei neue Teams in der RHL. Die Wild Boars Ebersberg gehen in der &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2018\/09\/14\/die-rhl-startet-mit-23-teams-in-die-neue-saison\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;Die RHL startet mit 23 Teams in die neue Saison !!!!&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":5198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3,25,23,24,49],"tags":[85],"class_list":["post-5373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","category-ligapokal","category-rhl-1","category-rhl-2","category-rhl-3","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=5373"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5373\/revisions"}],"predecessor-version":[{"id":5374,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5373\/revisions\/5374"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/5198"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=5373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=5373"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=5373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}