{"id":5371,"date":"2018-09-14T14:41:40","date_gmt":"2018-09-14T12:41:40","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=5371"},"modified":"2018-09-14T14:41:40","modified_gmt":"2018-09-14T12:41:40","slug":"icemonkeys-kolbermoor-suchen-spieler","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2018\/09\/14\/icemonkeys-kolbermoor-suchen-spieler\/","title":{"rendered":"Icemonkeys Kolbermoor suchen Spieler :)"},"content":{"rendered":"<p><strong>Hallo Eishockey Freunde,<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>wir die Icemonkeys Kolbermoor sind ein Junges dynamisches Team und auf der Suche nach Verst\u00e4rkungen.<\/strong><\/p>\n<p><strong>Wir spielen seit 6 Jahren in der RHL und sind im Moment in der 3. Liga zu finden. Wir w\u00fcrden gerne wieder etwas weiter oben mitspielen und w\u00fcrden uns freuen wenn wir ein paar Jungs dazu bekommen, die uns sportlich weiterhelfen. Du solltest schon mal in einer Hobbyliga gespielt haben und wissen wie man den Schl\u00e4ger in die Hand nimmt.<\/strong><\/p>\n<p><strong>Wir k\u00f6nnen dir von August &#8211; April regelm\u00e4\u00dfige w\u00f6chentliche Eiszeiten bieten. Wir werden diese Saison wieder ann\u00e4hernd 60 Eiszeiten haben.<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Wir haben jede Woche in Bad Aibling im wechsel Mittwoch\/Donnerstag jeweils von 22:15 &#8211; 23:15 Uhr Eis, zus\u00e4tzlich haben wir in Rosenheim alles 1-2 Wochen am Wochenende f\u00fcr 1,5 Std Eis und das ganze zu einem Hammerpreis.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Wenn du mehr erfahren willst, kannst du dich gern bei uns melden.<\/strong><\/p>\n<p><strong>Ansprechpartner: Daniel Kellermayer 0151\/12793649<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Matthias Tuschl\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0173\/2152324<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo Eishockey Freunde,\u00a0 wir die Icemonkeys Kolbermoor sind ein Junges dynamisches Team und auf der Suche nach Verst\u00e4rkungen. Wir spielen seit 6 Jahren in der RHL und sind im Moment in der 3. Liga zu finden. Wir w\u00fcrden gerne wieder etwas weiter oben mitspielen und w\u00fcrden uns freuen wenn wir ein paar Jungs dazu bekommen, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2018\/09\/14\/icemonkeys-kolbermoor-suchen-spieler\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;Icemonkeys Kolbermoor suchen Spieler :)&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":3187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,27,3,49],"tags":[85],"class_list":["post-5371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eiszeit","category-info","category-rhl-news","category-rhl-3","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=5371"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5371\/revisions"}],"predecessor-version":[{"id":5372,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/5371\/revisions\/5372"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/3187"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=5371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=5371"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=5371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}