{"id":4513,"date":"2017-12-19T00:28:01","date_gmt":"2017-12-18T23:28:01","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=4513"},"modified":"2017-12-26T17:09:05","modified_gmt":"2017-12-26T16:09:05","slug":"star-angels-vs-bluewings-33","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2017\/12\/19\/star-angels-vs-bluewings-33\/","title":{"rendered":"Star Angels vs. Bluewings 3:3"},"content":{"rendered":"<p><strong>Leistungsgerechtes Unentschieden der RHL-Neueinsteiger.<\/strong><\/p>\n<p>&#8211;BERICHT Star Angels:\u00a0Im allerersten Aufeinandertreffen beider Teams entwickelte sich eine rassige und bis zum Schlusspfiff spannende Partie beider Mannschaften.\u00a0 Am Ende stand ein gerechtes Unentschieden<strong>\u00a03:3 (0:1, 2:1, 1:1)<\/strong>\u00a0fest. Der Gegner begann \u00fcberrachsend stark mit fr\u00fchem Vorchecking und hoher Laufarbeit, damit kam man auf Seiten der<strong>Star Angels<\/strong>\u00a0anfangs nicht so zu recht und in dieser Phase fiel auch das<strong>\u00a00:1<\/strong>\u00a0f\u00fcr die\u00a0<strong>Louisenthaler.<\/strong>\u00a0Im zweiten Dritttel sortierte man sich mehr auf das Gegenpressing und kam so immer mehr zu eigenen Chancen &#8211; trotzdem lauerte der Gegner akribisch auf dumme Scheibenverluste um seine schnellen Konter zu fahren. Man konnte dann das 2. Drittel doch mit\u00a0<strong>2:1<\/strong>\u00a0f\u00fcr sich entscheiden. Im Abschlussdrittel spielten dann beide Mannschaften mit offenem Visier und es ging hin und her &#8211; Chancen h\u00fcben wie dr\u00fcben aber beide Torh\u00fcter boten eine \u00fcberragende Partei an diesem Abend so das letztendlich ein gerechtes<strong>\u00a03:3\u00a0<\/strong>als Endstand notiert werden konnte. Im ganzen Spiel gab es in keiner Phase irgendwelche \u00fcberharten Aktionen bzw. Fouls und die wenigen Strafminuten waren letztlich Hobbyeishockeyfouls. Beide Teams wollten sch\u00f6nes und schnelles Hobbyeishockey spielen.<\/p>\n<p>GAMECENTER:\u00a0<a href=\"http:\/\/www.rhl-hockey.com\/w2\/event\/star-angels-rosenheim-vs-bluewings-loisenthal\/\">http:\/\/www.rhl-hockey.com\/w2\/event\/star-angels-rosenheim-vs-bluewings-loisenthal\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leistungsgerechtes Unentschieden der RHL-Neueinsteiger. &#8211;BERICHT Star Angels:\u00a0Im allerersten Aufeinandertreffen beider Teams entwickelte sich eine rassige und bis zum Schlusspfiff spannende Partie beider Mannschaften.\u00a0 Am Ende stand ein gerechtes Unentschieden\u00a03:3 (0:1, 2:1, 1:1)\u00a0fest. Der Gegner begann \u00fcberrachsend stark mit fr\u00fchem Vorchecking und hoher Laufarbeit, damit kam man auf Seiten derStar Angels\u00a0anfangs nicht so zu recht und &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2017\/12\/19\/star-angels-vs-bluewings-33\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;Star Angels vs. Bluewings 3:3&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":3175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3,49],"tags":[85],"class_list":["post-4513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","category-rhl-3","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=4513"}],"version-history":[{"count":2,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4513\/revisions"}],"predecessor-version":[{"id":4538,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4513\/revisions\/4538"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/3175"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=4513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=4513"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=4513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}