{"id":4510,"date":"2017-12-18T16:35:59","date_gmt":"2017-12-18T15:35:59","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=4510"},"modified":"2017-12-18T16:35:59","modified_gmt":"2017-12-18T15:35:59","slug":"bruckmuehl-vs-schlossberg-21","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2017\/12\/18\/bruckmuehl-vs-schlossberg-21\/","title":{"rendered":"Bruckm\u00fchl vs. Schlo\u00dfberg 2:1"},"content":{"rendered":"<p><strong>Der EHC Bruckm\u00fchl ist RHL-Herbstmeister nach einem Arbeitssieg gegen starke Schlo\u00dfberger.<\/strong><\/p>\n<p>&#8211;BERICHT Bruckm\u00fchl:\u00a0Am gestrigen Sonntag, 17.12.17 stand das letzte Vorrundenspiel in der RHL an. Gegner war der Aufsteiger Schlo\u00dfberg.<br \/>\nDem EHC standen zwei komplette Reihen zur Verf\u00fcgung. Nach den letzten souver\u00e4nen Leistungen erwischte Bruckm\u00fchl dieses Mal keinen guten Tag. Der Auftritt war insgesamt einfach nur entt\u00e4uschend. Man machte zwar Druck, konnte aber au\u00dfer einer baldigen 1 zu 0 F\u00fchrung keinen weiteren Torerfolg erzielen. Schlo\u00dfberg spielte taktisch \u00e4u\u00dferst gut und k\u00e4mpfte zudem aufopferungsvoll. Nach dem Ausgleich der G\u00e4ste wurden die Angriffe der Bruckm\u00fchler zwar heftiger, aber weiterhin nicht zielgerichteter. Gl\u00fccklicherweise gelang dem EHC Anfang des zweiten Drittel der F\u00fchrungstreffer zum 2 zu 1. Weitere Chancen auf beiden Seiten vereitelten beide Torh\u00fcter. Somit endete die Partie knapp 2 zu 1 f\u00fcr den EHC. An diesem Abend z\u00e4hlten am Ende nur die drei Punkte und dass sie als RHL Tabellenerster ins neue Jahr starten.<br \/>\nDas n\u00e4chste Spiel des EHC findet nach einer Eishockeypause erst am 06.01.2018 statt. Gegner sind dann im Ligapokal die Moordeife Bad Aibling.<\/p>\n<p>Bis dahin w\u00fcnschen wir allen eine sch\u00f6ne Weihnachtszeit und einen guten Rutsch ins Jahr 2018.<\/p>\n<p>EHC Tore:<br \/>\nM\u00e4rz (Schlosser), Alt A. (Alt M.)<\/p>\n<p>Strafminuten:<br \/>\n10 EHC\/ 6 Schlo\u00dfberg<\/p>\n<p>GAMECENTER:\u00a0<a href=\"http:\/\/www.rhl-hockey.com\/w2\/event\/ehc-bruckmuehl-vs-sv-schlossberg\/\">http:\/\/www.rhl-hockey.com\/w2\/event\/ehc-bruckmuehl-vs-sv-schlossberg\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der EHC Bruckm\u00fchl ist RHL-Herbstmeister nach einem Arbeitssieg gegen starke Schlo\u00dfberger. &#8211;BERICHT Bruckm\u00fchl:\u00a0Am gestrigen Sonntag, 17.12.17 stand das letzte Vorrundenspiel in der RHL an. Gegner war der Aufsteiger Schlo\u00dfberg. Dem EHC standen zwei komplette Reihen zur Verf\u00fcgung. Nach den letzten souver\u00e4nen Leistungen erwischte Bruckm\u00fchl dieses Mal keinen guten Tag. Der Auftritt war insgesamt einfach nur &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2017\/12\/18\/bruckmuehl-vs-schlossberg-21\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;Bruckm\u00fchl vs. Schlo\u00dfberg 2:1&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":3176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3,23],"tags":[85],"class_list":["post-4510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","category-rhl-1","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=4510"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4510\/revisions"}],"predecessor-version":[{"id":4511,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4510\/revisions\/4511"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/3176"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=4510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=4510"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=4510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}