{"id":4308,"date":"2017-11-10T01:06:32","date_gmt":"2017-11-10T00:06:32","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=4308"},"modified":"2017-11-10T01:06:32","modified_gmt":"2017-11-10T00:06:32","slug":"icemonkeys-vs-star-angels-14","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2017\/11\/10\/icemonkeys-vs-star-angels-14\/","title":{"rendered":"Icemonkeys vs. Star Angels 1:4"},"content":{"rendered":"<p><strong>Star Angels Rosenheim holen sich die ersten RHL Punkte in einem fairen Spiel ohne Strafen.<\/strong><\/p>\n<p>&#8211;Bericht folgt!<br \/>\nLeider verletzte sich der Icemonkeys Spieler #18 Christian Kleeblatt in der 27. Spielminute, da er sich ungl\u00fccklich das Knie verdrehte. Wir w\u00fcnschen ihm gute Besserung!!!<\/p>\n<p>GAMECENTER:\u00a0<a href=\"http:\/\/www.rhl-hockey.com\/w2\/event\/icemonkeys-kolbermoor-vs-star-angels-rosenheim\/\">http:\/\/www.rhl-hockey.com\/w2\/event\/icemonkeys-kolbermoor-vs-star-angels-rosenheim\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Star Angels Rosenheim holen sich die ersten RHL Punkte in einem fairen Spiel ohne Strafen. &#8211;Bericht folgt! Leider verletzte sich der Icemonkeys Spieler #18 Christian Kleeblatt in der 27. Spielminute, da er sich ungl\u00fccklich das Knie verdrehte. Wir w\u00fcnschen ihm gute Besserung!!! GAMECENTER:\u00a0http:\/\/www.rhl-hockey.com\/w2\/event\/icemonkeys-kolbermoor-vs-star-angels-rosenheim\/<\/p>\n","protected":false},"author":1,"featured_media":3175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3,49],"tags":[85],"class_list":["post-4308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","category-rhl-3","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=4308"}],"version-history":[{"count":1,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4308\/revisions"}],"predecessor-version":[{"id":4309,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/4308\/revisions\/4309"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/3175"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=4308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=4308"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=4308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}