{"id":3220,"date":"2017-08-28T15:07:45","date_gmt":"2017-08-28T13:07:45","guid":{"rendered":"http:\/\/www.rhl-hockey.com\/w2\/?p=3220"},"modified":"2017-08-29T11:31:50","modified_gmt":"2017-08-29T09:31:50","slug":"facebook-whatsapp-usw-neue-professionelle-rhl-ligenstatistik-und-mehr-auf-der-rhl-webseite","status":"publish","type":"post","link":"http:\/\/www.rhl-hockey.com\/w2\/2017\/08\/28\/facebook-whatsapp-usw-neue-professionelle-rhl-ligenstatistik-und-mehr-auf-der-rhl-webseite\/","title":{"rendered":"FACEBOOK &#8211; WHATSAPP usw. NEUE PROFESSIONELLE RHL LIGENSTATISTIK UND MEHR AUF DER RHL WEBSEITE"},"content":{"rendered":"<p>So&#8230;.<strong>FACEBOOK<\/strong> ist ja gut und sch\u00f6n, jedoch werden wir in Zukunft die Beitr\u00e4ge hier drastisch reduzieren und nicht jedes Ergebnis ver\u00f6ffentlichen.<br \/>\nDer Zeitaufwand hierf\u00fcr steht in keiner Relation um alles doppelt bekanntzugeben. Dazu haben wir unsere <strong>RHL-WEBSEITE.<\/strong><\/p>\n<p><strong>RHL WEBSEITE:<\/strong> In der kommenden 38. Spielzeit der RHL steht uns nun ein neues professionelles und zeitgem\u00e4\u00dfes Statistiktool f\u00fcr unsere Webseite (Im kommenden Januar werden es 20 Jahre!!!!) zur Verf\u00fcgung, das in der letzten Woche von mir aufwendig integriert wurde.<br \/>\nHier k\u00f6nnen nun nicht nur alle wichtigen Informationen, News abgerufen werden, sondern auch <strong>ALLE<\/strong> Statistiken zu den teilnehmenden Mannschaften\/Ansprechpartner der RHL Wettbewerbe,\u00a0 und zu den einzelnen gemeldeten und spielberechtigten Spielern in der RHL schnell und informativ abgerufen werden. (Dazu klickt man nur auf das Team oder den Spielernamen)<br \/>\nAngaben zu Geburtdatum, Gr\u00f6\u00dfe, Gewicht usw. wird es jedoch nicht geben (w\u00e4re zwar alles m\u00f6glich), da mir der <strong>DATENSCHUTZ<\/strong> f\u00fcr die einzelnen Spieler wichtiger ist.<br \/>\nDie RHL Ligadaten werden in den kommenden Wochen erg\u00e4nzt, wenn die Teamleiter ihre Mannschaftslisten\/Mitarbeiter sowie ihre Spieldaten bei mir komplett eingereicht haben.<br \/>\nSomit steht Euch nun eine pofessionelle Ligawebseite zur Verf\u00fcgung, mit der wir uns nun wirklich nicht vor den gro\u00dfen internationalen Eishockeyligen verstecken m\u00fcssen!<br \/>\nUnsere hohen Zugiffszahlen auf unsere RHL Webseite aus vielen internationalen L\u00e4ndern best\u00e4tigen dies.<\/p>\n<p>Eine seperate App f\u00fcr die RHL zu entwickeln ist \u00fcberfl\u00fcssig, da unsere Webseite alle modenen Anforderungen f\u00fcr alle g\u00e4ngigen und aktuellen Systeme unterst\u00fctzt.<\/p>\n<p><strong>WHATSAPP vs. TELEGAM MESSENGER:<\/strong> Wer nun noch schneller alle TOP-INFOS\/NEWS der RHL auf dem Smartphone haben will, sollte sich den Telegram Messenger auf sein Handy installieren und den RHL-Channel abonieren, da dies leider bis heute bei dem doch so angeblich tollen WHATSAPP Massanger (Ironie) zur Integration f\u00fcr Websites nicht m\u00f6glich ist.<br \/>\nEine Anleitung dazu findet ihr hier: <a href=\"http:\/\/www.rhl-hockey.com\/w2\/2017\/07\/28\/rhl-hockey-channal-im-telegram-messenger\/\">http:\/\/www.rhl-hockey.com\/w2\/2017\/07\/28\/rhl-hockey-channal-im-telegram-messenger\/<\/a><br \/>\nDie, die bereits den RHL-Channel aboniert haben werden dies best\u00e4tigen, da dieser Messenger sogar noch mehr Features bietet wie WA.<\/p>\n<p><strong>So nun viel Spa\u00df auf der &#8222;neuen&#8220; RHL-Webseite. http:\/\/www.rhl-hockey.com<\/strong><\/p>\n<p>Mit sportlichen Gr\u00fc\u00dfen &#8211; Der Webmaster der RHL \ud83d\ude09<\/p>\n<p>PS: Wer Fehler findet oder Verbesserungsvorschl\u00e4ge hat kann sich gerne an mich wenden \ud83d\ude09 &#8211; SIEHE CONTACT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So&#8230;.FACEBOOK ist ja gut und sch\u00f6n, jedoch werden wir in Zukunft die Beitr\u00e4ge hier drastisch reduzieren und nicht jedes Ergebnis ver\u00f6ffentlichen. Der Zeitaufwand hierf\u00fcr steht in keiner Relation um alles doppelt bekanntzugeben. Dazu haben wir unsere RHL-WEBSEITE. RHL WEBSEITE: In der kommenden 38. Spielzeit der RHL steht uns nun ein neues professionelles und zeitgem\u00e4\u00dfes Statistiktool &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.rhl-hockey.com\/w2\/2017\/08\/28\/facebook-whatsapp-usw-neue-professionelle-rhl-ligenstatistik-und-mehr-auf-der-rhl-webseite\/\" class=\"more-link\">Mehr <span class=\"screen-reader-text\">\u00fcber &#8222;FACEBOOK &#8211; WHATSAPP usw. NEUE PROFESSIONELLE RHL LIGENSTATISTIK UND MEHR AUF DER RHL WEBSEITE&#8220; <\/span>Lesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":3187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,3],"tags":[56,85],"class_list":["post-3220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","category-rhl-news","tag-rhl-rosenheim-hockey-league-eishockey","tag-rhl-rosenheim-hockey-league-eishockey-eishockey-rosenheim"],"_links":{"self":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/3220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/comments?post=3220"}],"version-history":[{"count":5,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/3220\/revisions"}],"predecessor-version":[{"id":3239,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/posts\/3220\/revisions\/3239"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media\/3187"}],"wp:attachment":[{"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/media?parent=3220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/categories?post=3220"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rhl-hockey.com\/w2\/wp-json\/wp\/v2\/tags?post=3220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}